{"id":2590,"date":"2026-01-29T16:31:41","date_gmt":"2026-01-29T13:31:41","guid":{"rendered":"https:\/\/kalinkamagazin.com\/product\/4154-tortitas-frito-con-relleno-de-queso-fresco-con-sabor-a-vainilla-30-congelado-es\/"},"modified":"2026-01-29T16:57:18","modified_gmt":"2026-01-29T13:57:18","slug":"4154-tortitas-frito-con-relleno-de-queso-fresco-con-sabor-a-vainilla-30-congelado-es","status":"publish","type":"product","link":"https:\/\/kalinkamagazin.com\/es\/product\/4154-tortitas-frito-con-relleno-de-queso-fresco-con-sabor-a-vainilla-30-congelado-es\/","title":{"rendered":"Tortitas, frito, con relleno de queso fresco con sabor a vainilla (30%), congelado"},"content":{"rendered":"<p>Panqueques horneados con relleno de queso crema con sabor a vainilla (30 %), congelados. Ingredientes: Queso crema 25 %, leche, harina de trigo, huevo entero de gallina 6 %, az\u00facar, aceite de girasol, crema agria, sal, levadura, bicarbonato de sodio, aroma de vainilla. No volver a congelar el producto descongelado. Consumir inmediatamente despu\u00e9s de descongelarlo. Instrucciones de cocci\u00f3n: Descongelar en el microondas durante unos 30 segundos. Fabricante: Lackmann Fleisch- und Feinkostfabrik GmbH, Carl-Benz Stra\u00dfe 10, 77731 Willst\u00e4tt. Consumir preferentemente antes de \u2264 -18 \u00b0C: ver etiqueta. <!--NWT-Text-->Valor nutricional por 100 g: Valor energ\u00e9tico: 1021 kJ \/ 243 kcal, Grasas: 9,8 g, de las cuales saturadas: 3,5 g, Hidratos de carbono: 26 g, de los cuales az\u00facares: 8,4 g, Prote\u00ednas: 13 g, Sal: 0,84 g, <!--NWT-Table--><\/p>\n<table>\n<tbody>\n<tr>\n<td colspan=\"2\">Valor nutricional por 100 g:<\/td>\n<\/tr>\n<tr>\n<td>Valor energ\u00e9tico:<\/td>\n<td align = \"right\">1021 kJ\/243 kcal<\/td>\n<\/tr>\n<tr>\n<td>Grasas:<\/td>\n<td align = \"right\">9,8 g<\/td>\n<\/tr>\n<tr>\n<td>de las cuales saturadas:<\/td>\n<td align = \"right\">3,5 g<\/td>\n<\/tr>\n<tr>\n<td>Hidratos de carbono:<\/td>\n<td align = \"right\">26 g<\/td>\n<\/tr>\n<tr>\n<td>- de los cuales az\u00facares:<\/td>\n<td align = \"right\">8,4 g<\/td>\n<\/tr>\n<tr>\n<td>Prote\u00ednas:<\/td>\n<td align = \"right\">13 g<\/td>\n<\/tr>\n<tr>\n<td>Sal:<\/td>\n<td align = \"right\">0,84 g<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <!--Bezeichnung-->Panqueques horneados con relleno de queso crema con sabor a vainilla (30 %), congelados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Panqueques horneados con relleno de queso crema con sabor a vainilla (30 %), congelados. Ingredientes: Queso crema 25 %, leche, harina de trigo, huevo entero de gallina 6 %, az\u00facar, aceite de girasol, crema agria, sal, levadura, bicarbonato de sodio, aroma de vainilla. No volver a congelar el producto descongelado. Consumir inmediatamente despu\u00e9s de descongelarlo. [&hellip;]<\/p>\n","protected":false},"featured_media":1963,"template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[187,189],"product_tag":[],"class_list":{"0":"post-2590","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-productos-congelados-y-pan","7":"product_cat-productos-de-masa-congelados","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/product\/2590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/media\/1963"}],"wp:attachment":[{"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/media?parent=2590"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/product_brand?post=2590"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/product_cat?post=2590"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/product_tag?post=2590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}