{"id":4768,"date":"2026-01-28T15:06:04","date_gmt":"2026-01-28T12:06:04","guid":{"rendered":"https:\/\/kalinkamagazin.com\/product\/00025441-setas-gruzdi-marinadas-12x660gremela-es\/"},"modified":"2026-05-04T16:50:07","modified_gmt":"2026-05-04T13:50:07","slug":"00025441-setas-gruzdi-marinadas-12x660gremela-es","status":"publish","type":"product","link":"https:\/\/kalinkamagazin.com\/es\/product\/00025441-setas-gruzdi-marinadas-12x660gremela-es\/","title":{"rendered":"Setas GRUZDI marinadas 12x660gr.EMELA"},"content":{"rendered":"<p>\"-\"<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\"-\"<\/p>\n","protected":false},"featured_media":3930,"template":"","meta":{"inline_featured_image":false},"product_brand":[],"product_cat":[197,134,128],"product_tag":[],"class_list":{"0":"post-4768","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-setas-hongos-en-conserva","7":"product_cat-griby-konservirovannye","8":"product_cat-konservacziya","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/product\/4768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/media\/3930"}],"wp:attachment":[{"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/media?parent=4768"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/product_brand?post=4768"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/product_cat?post=4768"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/product_tag?post=4768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}