{"id":237,"count":14,"description":"","link":"https:\/\/kalinkamagazin.com\/es\/product-category\/pescado-y-productos-de-pescado\/salado-ahumado-seco-curado\/","name":"Salado \/ ahumado \/ seco (curado)","slug":"salado-ahumado-seco-curado","taxonomy":"product_cat","parent":232,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/product_cat\/237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/product_cat\/232"}],"wp:post_type":[{"href":"https:\/\/kalinkamagazin.com\/es\/wp-json\/wp\/v2\/product?product_cat=237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}